{"id":3159,"date":"2025-12-03T18:38:17","date_gmt":"2025-12-03T10:38:17","guid":{"rendered":"https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube.jpg"},"modified":"2025-12-03T18:38:24","modified_gmt":"2025-12-03T10:38:24","slug":"flexible-tube","status":"inherit","type":"attachment","link":"https:\/\/www.hosonwater.com\/it\/?attachment_id=3159","title":{"rendered":"Tubo flessibile"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-3159","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Flexible Tube\" srcset=\"https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-300x300.jpg 300w, https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-150x150.jpg 150w, https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-768x768.jpg 768w, https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-600x600.jpg 600w, https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-100x100.jpg 100w, https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Flexible Tube","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":800,"file":"2025\/12\/Flexible-Tube.jpg","filesize":82095,"sizes":{"medium":{"file":"Flexible-Tube-300x300.jpg","width":300,"height":300,"filesize":7287,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-300x300.jpg"},"thumbnail":{"file":"Flexible-Tube-150x150.jpg","width":150,"height":150,"filesize":2877,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-150x150.jpg"},"medium_large":{"file":"Flexible-Tube-768x768.jpg","width":768,"height":768,"filesize":29119,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-768x768.jpg"},"woocommerce_thumbnail":{"file":"Flexible-Tube-300x300.jpg","width":300,"height":300,"filesize":7287,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-300x300.jpg"},"woocommerce_single":{"file":"Flexible-Tube-600x600.jpg","width":600,"height":600,"filesize":20374,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-600x600.jpg"},"woocommerce_gallery_thumbnail":{"file":"Flexible-Tube-100x100.jpg","width":100,"height":100,"filesize":1844,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube-100x100.jpg"},"full":{"file":"Flexible-Tube.jpg","width":800,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3158,"source_url":"https:\/\/www.hosonwater.com\/wp-content\/uploads\/2025\/12\/Flexible-Tube.jpg","_links":{"self":[{"href":"https:\/\/www.hosonwater.com\/it\/wp-json\/wp\/v2\/media\/3159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hosonwater.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.hosonwater.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.hosonwater.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hosonwater.com\/it\/wp-json\/wp\/v2\/comments?post=3159"}]}}